{"id":30125,"date":"2026-07-09T11:00:16","date_gmt":"2026-07-09T09:00:16","guid":{"rendered":"https:\/\/www.sera.asso.fr\/?p=30125"},"modified":"2026-07-15T22:29:17","modified_gmt":"2026-07-15T20:29:17","slug":"de-multiples-incendies-impactent-la-pollution-atmospherique-sur-de-nombreux-territoires","status":"publish","type":"post","link":"https:\/\/www.sera.asso.fr\/index.php\/de-multiples-incendies-impactent-la-pollution-atmospherique-sur-de-nombreux-territoires\/","title":{"rendered":"De multiples incendies impactent la pollution atmosph\u00e9rique sur de nombreux territoires"},"content":{"rendered":"<p style=\"text-align: justify;\">&#xA0;La pollution atmosph&#xE9;rique due aux feux de for&#xEA;ts contribuerait &#xE0; plus de 13 % de la surmortalit&#xE9; totale en Europe attribuable &#xE0; la pollution par les particules fines (PM2.5) selon les r&#xE9;sultats du projet Exhaustion rapport&#xE9;s par l&#x2019;Organisation de coop&#xE9;ration et de d&#xE9;veloppement &#xE9;conomique (<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;OCDE&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Organisation de Coop&#xE9;ration et de D&#xE9;veloppement &#xC9;conomique&lt;\/div&gt;\" href=\"https:\/\/www.sera.asso.fr\/index.php\/glossaire\/ocde\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">OCDE<\/a>).<\/p>\n<p style=\"text-align: justify;\">l&#x2019;Association AtmoSud a rassembl&#xE9; les principaux enseignements de la litt&#xE9;rature scientifique r&#xE9;cente sur les &#xE9;missions li&#xE9;es aux incendies, le transport des fum&#xE9;es, leurs effets sur la qualit&#xE9; de l&#x2019;air et la sant&#xE9;, ainsi que les enjeux de surveillance.<\/p>\n<p style=\"text-align: justify;\">Les fum&eacute;es &eacute;manant des feux contiennent un m&eacute;lange complexe de gaz, de compos&eacute;s organiques volatils (<a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;COV&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Compos&eacute;s Organiques Volatiles&lt;\/div&gt;\"  href=\"https:\/\/www.sera.asso.fr\/index.php\/glossaire\/cov\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]'  tabindex='0' role='link'>COV<\/a>) et d&rsquo;a&eacute;rosols de diff&eacute;rentes natures. Dans l&rsquo;atmosph&egrave;re, ces polluants primaires subissent des transformations physicochimiques qui peuvent donner naissance &agrave; des polluants secondaires. On peut y retrouver du dioxyde de carbone, du monoxyde de carbone, des oxydes d&rsquo;azote, du m&eacute;thane, ou encore de l&rsquo;ammoniac. Le type de feux (prairies, for&ecirc;ts&hellip;) peut donner lieu &agrave; des profils d&rsquo;&eacute;missions de fum&eacute;es tr&egrave;s diff&eacute;rents.<\/p>\n<p style=\"text-align: justify;\">Ces&#xA0; fum&#xE9;es (m&#xE9;lange de gaz, particules solides et gouttelettes &#xE9;mises par la combustion) engendr&#xE9;es par les incendies peuvent se d&#xE9;placer sur plusieurs centaines de kilom&#xE8;tres et ainsi contaminer diff&#xE9;rents milieux (air, eau, sol) et affecter des populations &#xE9;loign&#xE9;es g&#xE9;ographiquement, rappelons nous des feux canadiens qui l&#x2019;an dernier se sont d&#xE9;plac&#xE9;s sur la France, en traversant l&#x2019;oc&#xE9;an.<\/p>\n<p style=\"text-align: justify;\">Les m&#xE9;ga incendies de la foret de Fontainebleau ont provoqu&#xE9; des taux de particules fines d&#xE9;passant les concentrations en particules pour atteindre&#xA0; 400 microgrammes par m&#xE8;tre cube selon <a href=\"https:\/\/www.airparif.fr\/\" target=\"_blank\" rel=\"noopener\" data-tooltip-url=\"https:\/\/www.airparif.fr\/\">Ariparif&#xA0;<\/a>qui, conjugu&#xE9;es&#xA0; avec la canicule, pour laquelle&#xA0; des niveaux soutenus en ozone &#xE9;taient d&#xE9;j&#xE0; pr&#xE9;sents ( autre polluant) , font que malheureusement, c&#x2019;est la double peine pour les habitants &#xE0; proximit&#xE9; des feux.<\/p>\n<p style=\"text-align: justify;\">Selon l&#x2019;Agence nationale de s&#xE9;curit&#xE9; sanitaire (Anses), cit&#xE9;e dans la note, l&#x2019;inhalation &#xE0; court terme de fum&#xE9;es de bois alt&#xE8;re les m&#xE9;canismes de d&#xE9;fense immunitaire des poumons.<\/p>\n<p>https:\/\/www.atmo-auvergnerhonealpes.fr\/actualite\/incendie-dans-le-diois-26-mobilisation-pour-suivre-limpact-des-fumees<\/p>\n<p>https:\/\/www.atmosud.org\/publications\/etude-bibliographique-impact-des-feux-de-foret-sur-la-qualite-de-lair-2026<\/p>\n<p>https:\/\/www.prevair.org\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#xA0;La pollution atmosph&#xE9;rique due aux feux de for&#xEA;ts contribuerait &#xE0; plus de 13 % de la surmortalit&#xE9; totale en Europe attribuable &#xE0; la pollution par les particules fines (PM2.5) selon &#x2026; <a href=\"https:\/\/www.sera.asso.fr\/index.php\/de-multiples-incendies-impactent-la-pollution-atmospherique-sur-de-nombreux-territoires\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">De multiples incendies impactent la pollution atmosph&#xE9;rique sur de nombreux territoires<\/span> <span class=\"meta-nav\">&#x2192;<\/span><\/a><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[181,184,607,195,197,198,209,212,185,614,224,230,239,213],"tags":[],"class_list":["post-30125","post","type-post","status-publish","format-standard","hentry","category-agriculture_elevage","category-air","category-aspects-reglementaires","category-biodiversite","category-changements_climatiques","category-contanimations_chimiques","category-energies","category-etudes_scientifiques","category-air_ext","category-modes-de-comportement","category-population_risque","category-vie_quotidienne","category-surveillance-sanitaire","category-toxicologique"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/posts\/30125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/comments?post=30125"}],"version-history":[{"count":3,"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/posts\/30125\/revisions"}],"predecessor-version":[{"id":30158,"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/posts\/30125\/revisions\/30158"}],"wp:attachment":[{"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/media?parent=30125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/categories?post=30125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sera.asso.fr\/index.php\/wp-json\/wp\/v2\/tags?post=30125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}